{"id":6503,"date":"2024-12-18T11:36:07","date_gmt":"2024-12-18T10:36:07","guid":{"rendered":"https:\/\/sailproof.shop\/product\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/"},"modified":"2026-03-31T17:40:39","modified_gmt":"2026-03-31T16:40:39","slug":"cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x","status":"publish","type":"product","link":"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/","title":{"rendered":"Cable conector USB a CC para SP10, SP08S y SP08X"},"content":{"rendered":"<p>Cable de carga compatible con SP10, SP08S y SP08X, no compatible con SP08AS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conector USB-A a CC para cargar la tableta SP10, SP08s y SP08X<\/p>\n","protected":false},"featured_media":5692,"template":"","meta":[],"product_brand":[904],"product_cat":[664],"product_tag":[742,743],"class_list":{"0":"post-6503","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-sailproof","7":"product_cat-accesorios-para-tabletas-resistentes","8":"product_tag-2-anos-de-garantia","9":"product_tag-entrega-rapida","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"supplier_id":null,"supplier_sku":"","barcode":null,"atum_controlled":true,"out_stock_date":null,"out_stock_threshold":null,"inheritable":false,"inbound_stock":0,"stock_on_hold":0,"sold_today":0,"sales_last_days":0,"out_stock_days":0,"lost_sales":0,"has_location":false,"update_date":"2026-05-13T00:04:48","atum_locations":[],"atum_stock_status":"instock","restock_status":false,"low_stock_amount":4,"sales_update_date":"2026-05-13T00:04:48","calc_backorders":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cable conector USB a CC para SP10, SP08S y SP08X - SailProof shop<\/title>\n<meta name=\"description\" content=\"Cable USB-A a conector CC para cargar la tableta robusta SailProof SP10, SP08S y SP08X\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cable conector USB a CC para SP10, SP08S y SP08X - SailProof shop\" \/>\n<meta property=\"og:description\" content=\"Cable USB-A a conector CC para cargar la tableta robusta SailProof SP10, SP08S y SP08X\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/\" \/>\n<meta property=\"og:site_name\" content=\"SailProof shop\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sailproof\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T16:40:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sailproof.shop\/wp-content\/uploads\/2024\/12\/SPR94_SailProof_USBtoDC_SP10-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SailproofShop\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/producto\\\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\\\/\",\"url\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/producto\\\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\\\/\",\"name\":\"Cable conector USB a CC para SP10, SP08S y SP08X - SailProof shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/producto\\\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/producto\\\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sailproof.shop\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SPR94_SailProof_USBtoDC_SP10-min.jpg\",\"datePublished\":\"2024-12-18T10:36:07+00:00\",\"dateModified\":\"2026-03-31T16:40:39+00:00\",\"description\":\"Cable USB-A a conector CC para cargar la tableta robusta SailProof SP10, SP08S y SP08X\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/producto\\\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sailproof.shop\\\/es\\\/producto\\\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/producto\\\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sailproof.shop\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SPR94_SailProof_USBtoDC_SP10-min.jpg\",\"contentUrl\":\"https:\\\/\\\/sailproof.shop\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/SPR94_SailProof_USBtoDC_SP10-min.jpg\",\"width\":750,\"height\":750,\"caption\":\"SailProof USB-A to DC jack cable for SP10 rugged tablet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/producto\\\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Accesorios\",\"item\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/categoria-producto\\\/accesorios\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Accesorios para tabletas resistentes\",\"item\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/categoria-producto\\\/accesorios\\\/accesorios-para-tabletas-resistentes\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Cable conector USB a CC para SP10, SP08S y SP08X\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/\",\"name\":\"SailProof Shop\",\"description\":\"Rugged tablets and waterproof electronic device for sailors\",\"publisher\":{\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/#organization\"},\"alternateName\":\"SailProof Shop\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/#organization\",\"name\":\"SailProof Shop\",\"url\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sailproof.shop\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Logo-SailProof.png\",\"contentUrl\":\"https:\\\/\\\/sailproof.shop\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Logo-SailProof.png\",\"width\":160,\"height\":57,\"caption\":\"SailProof Shop\"},\"image\":{\"@id\":\"https:\\\/\\\/sailproof.shop\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sailproof\",\"https:\\\/\\\/x.com\\\/SailproofShop\",\"https:\\\/\\\/instagram.com\\\/sail.proof\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sailproofshop\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/SailProof\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClR4lWJvI8KoSGnCbLYPaFg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cable conector USB a CC para SP10, SP08S y SP08X - SailProof shop","description":"Cable USB-A a conector CC para cargar la tableta robusta SailProof SP10, SP08S y SP08X","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/","og_locale":"es_ES","og_type":"article","og_title":"Cable conector USB a CC para SP10, SP08S y SP08X - SailProof shop","og_description":"Cable USB-A a conector CC para cargar la tableta robusta SailProof SP10, SP08S y SP08X","og_url":"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/","og_site_name":"SailProof shop","article_publisher":"https:\/\/www.facebook.com\/sailproof","article_modified_time":"2026-03-31T16:40:39+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/sailproof.shop\/wp-content\/uploads\/2024\/12\/SPR94_SailProof_USBtoDC_SP10-min.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SailproofShop","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/","url":"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/","name":"Cable conector USB a CC para SP10, SP08S y SP08X - SailProof shop","isPartOf":{"@id":"https:\/\/sailproof.shop\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/#primaryimage"},"image":{"@id":"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/#primaryimage"},"thumbnailUrl":"https:\/\/sailproof.shop\/wp-content\/uploads\/2024\/12\/SPR94_SailProof_USBtoDC_SP10-min.jpg","datePublished":"2024-12-18T10:36:07+00:00","dateModified":"2026-03-31T16:40:39+00:00","description":"Cable USB-A a conector CC para cargar la tableta robusta SailProof SP10, SP08S y SP08X","breadcrumb":{"@id":"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/#primaryimage","url":"https:\/\/sailproof.shop\/wp-content\/uploads\/2024\/12\/SPR94_SailProof_USBtoDC_SP10-min.jpg","contentUrl":"https:\/\/sailproof.shop\/wp-content\/uploads\/2024\/12\/SPR94_SailProof_USBtoDC_SP10-min.jpg","width":750,"height":750,"caption":"SailProof USB-A to DC jack cable for SP10 rugged tablet"},{"@type":"BreadcrumbList","@id":"https:\/\/sailproof.shop\/es\/producto\/cable-conector-usb-a-cc-para-sp10-sp08s-y-sp08x\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sailproof.shop\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/sailproof.shop\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Accesorios","item":"https:\/\/sailproof.shop\/es\/categoria-producto\/accesorios\/"},{"@type":"ListItem","position":4,"name":"Accesorios para tabletas resistentes","item":"https:\/\/sailproof.shop\/es\/categoria-producto\/accesorios\/accesorios-para-tabletas-resistentes\/"},{"@type":"ListItem","position":5,"name":"Cable conector USB a CC para SP10, SP08S y SP08X"}]},{"@type":"WebSite","@id":"https:\/\/sailproof.shop\/es\/#website","url":"https:\/\/sailproof.shop\/es\/","name":"SailProof Shop","description":"Rugged tablets and waterproof electronic device for sailors","publisher":{"@id":"https:\/\/sailproof.shop\/es\/#organization"},"alternateName":"SailProof Shop","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sailproof.shop\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sailproof.shop\/es\/#organization","name":"SailProof Shop","url":"https:\/\/sailproof.shop\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sailproof.shop\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sailproof.shop\/wp-content\/uploads\/2024\/10\/Logo-SailProof.png","contentUrl":"https:\/\/sailproof.shop\/wp-content\/uploads\/2024\/10\/Logo-SailProof.png","width":160,"height":57,"caption":"SailProof Shop"},"image":{"@id":"https:\/\/sailproof.shop\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sailproof","https:\/\/x.com\/SailproofShop","https:\/\/instagram.com\/sail.proof","https:\/\/www.linkedin.com\/company\/sailproofshop\/","https:\/\/www.pinterest.com\/SailProof\/","https:\/\/www.youtube.com\/channel\/UClR4lWJvI8KoSGnCbLYPaFg"]}]}},"_links":{"self":[{"href":"https:\/\/sailproof.shop\/es\/wp-json\/wp\/v2\/product\/6503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sailproof.shop\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sailproof.shop\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sailproof.shop\/es\/wp-json\/wp\/v2\/media\/5692"}],"wp:attachment":[{"href":"https:\/\/sailproof.shop\/es\/wp-json\/wp\/v2\/media?parent=6503"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sailproof.shop\/es\/wp-json\/wp\/v2\/product_brand?post=6503"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sailproof.shop\/es\/wp-json\/wp\/v2\/product_cat?post=6503"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sailproof.shop\/es\/wp-json\/wp\/v2\/product_tag?post=6503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}